{"id":48257,"date":"2026-03-31T14:13:38","date_gmt":"2026-03-31T12:13:38","guid":{"rendered":"https:\/\/boutique.laventure.michelin.com\/produit\/guide-vert-japon-ebook-2\/"},"modified":"2026-04-14T11:35:49","modified_gmt":"2026-04-14T09:35:49","slug":"guide-vert-japon-ebook-2","status":"publish","type":"product","link":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/","title":{"rendered":"Guide Vert Japon &#8211; ebook"},"content":{"rendered":"<p>Laissez-vous guider par nos auteurs ! Au cours de leurs innombrables tourn&#xE9;es, ils ont d&#xE9;nich&#xE9; pour vous des lieux inoubliables ou insolites :<\/p>\n<p><strong>&#8211; Les incontournables (class&#xE9;s 1, 2 ou 3 &#xE9;toiles) :<\/strong>&#xA0;Kyoto***, Le mont Fuji***, Baie de Kabira*** &#8230;<\/p>\n<p><strong>&#8211; Les coups de coeur :<\/strong>&#xA0;Plonger dans les eaux transparentes de l&#x2019;&#xEE;le subtropicale de Yoron ; Franchir les portes sacr&#xE9;es au Fushimi&#x2011;Inari Taisha ; Vibrer avec les Japonais &#xE0; un combat de sumo &#8230;<\/p>\n<p><strong>&#8211; Les bonnes adresses pour tous les budgets :<\/strong>&#xA0;se restaurer, prendre un verre, shopping, sortir, se loger<\/p>\n<p><strong>&#8211; Les meilleurs spots en famille (activit&#xE9;s pour les 6-14 ans) :<\/strong>&#xA0;Plong&#xE9;e dans la magie des anime ; Promenade au milieu des cerfs Sika ; Vir&#xE9;e dans le d&#xE9;sert &#xE0; dos de chameau &#8230;<\/p>\n<p><strong>&#8211; Des suggestions d&#x2019;itin&#xE9;raires :<\/strong>&#xA0;Cap au sud : Kyushu et les archipels en 20 jours ; La route du Tokaido en 14 jours ; Autour de la mer Int&#xE9;rieure en 10 jours &#8230;<\/p>\n<p><strong>&#8211; De nombreux cartes et plans<\/strong>&#xA0;pour retrouver les principaux sites &#xE9;toil&#xE9;s de la destination.<\/p>\n<p><strong>&#8211; Les plus :&#xA0;<\/strong>120 activit&#xE9;s en famille<\/p>\n<p><strong>&#8211; Toutes les infos mises &#xE0; jour<\/strong>&#xA0;dans cette nouvelle &#xE9;dition<\/p>\n<p><strong>Ce guide est divis&#xE9; en 9 micro-r&#xE9;gions :<\/strong>&#xA0;Tokyo et sa r&#xE9;gion ; Centre de Honshu (Chubu) ; Kyoto et le Kansai ; Ouest de Honshu (Chugoku) ; Nord de Honshu (Tohoku) ; Hokkaido ; Shikoku ; Kyushu ; Les archipels du Sud.<\/p>\n<p>Pensez &#xE0; utilisez en compl&#xE9;ment notre&#xA0;<strong>Carte National Japon n&#xB0;802, notre Guide Vert Week&amp;GO Tokyo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laissez-vous guider par nos auteurs ! Au cours de leurs innombrables tourn&#xE9;es, ils ont d&#xE9;nich&#xE9; pour vous des lieux inoubliables ou insolites :<\/p>\n<p><strong>&#8211; Les incontournables (class&#xE9;s 1, 2 ou 3 &#xE9;toiles) :<\/strong>&#xA0;Kyoto***, Le mont Fuji***, Baie de Kabira*** &#8230;<\/p>\n<p><strong>&#8211; Les coups de coeur :<\/strong>&#xA0;Plonger dans les eaux transparentes de l&#x2019;&#xEE;le subtropicale de Yoron ; Franchir les portes sacr&#xE9;es au Fushimi&#x2011;Inari Taisha ; Vibrer avec les Japonais &#xE0; un combat de sumo &#8230;<\/p>\n<p><strong>&#8211; Les bonnes adresses pour tous les budgets :<\/strong>&#xA0;se restaurer, prendre un verre, shopping, sortir, se loger<\/p>\n<p><strong>&#8211; Les meilleurs spots en famille (activit&#xE9;s pour les 6-14 ans) :<\/strong>&#xA0;Plong&#xE9;e dans la magie des anime ; Promenade au milieu des cerfs Sika ; Vir&#xE9;e dans le d&#xE9;sert &#xE0; dos de chameau &#8230;<\/p>\n<p><strong>&#8211; Des suggestions d&#x2019;itin&#xE9;raires :<\/strong>&#xA0;Cap au sud : Kyushu et les archipels en 20 jours ; La route du Tokaido en 14 jours ; Autour de la mer Int&#xE9;rieure en 10 jours &#8230;<\/p>\n<p><strong>&#8211; De nombreux cartes et plans<\/strong>&#xA0;pour retrouver les principaux sites &#xE9;toil&#xE9;s de la destination.<\/p>\n<p><strong>&#8211; Les plus :&#xA0;<\/strong>120 activit&#xE9;s en famille<\/p>\n<p><strong>&#8211; Toutes les infos mises &#xE0; jour<\/strong>&#xA0;dans cette nouvelle &#xE9;dition<\/p>\n<p><strong>Ce guide est divis&#xE9; en 9 micro-r&#xE9;gions :<\/strong>&#xA0;Tokyo et sa r&#xE9;gion ; Centre de Honshu (Chubu) ; Kyoto et le Kansai ; Ouest de Honshu (Chugoku) ; Nord de Honshu (Tohoku) ; Hokkaido ; Shikoku ; Kyushu ; Les archipels du Sud.<\/p>\n<p>Pensez &#xE0; utilisez en compl&#xE9;ment notre&#xA0;<strong>Carte National Japon n&#xB0;802, notre Guide Vert Week&amp;GO Tokyo.<\/strong><\/p>\n","protected":false},"featured_media":48255,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[329],"product_tag":[],"class_list":{"0":"post-48257","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ebook-en","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","10":"ast-product-gallery-layout-horizontal-slider","11":"ast-product-gallery-with-no-image","12":"ast-product-tabs-layout-horizontal","14":"first","15":"instock","16":"downloadable","17":"virtual","18":"taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin\" \/>\n<meta property=\"og:description\" content=\"Laissez-vous guider par nos auteurs ! Au cours de leurs innombrables tourn&#xE9;es, ils ont d&#xE9;nich&#xE9; pour vous des lieux inoubliables ou insolites : - Les incontournables (class&#xE9;s 1, 2 ou 3 &#xE9;toiles) :&#xA0;Kyoto***, Le mont Fuji***, Baie de Kabira*** ... - Les coups de coeur :&#xA0;Plonger dans les eaux transparentes de l&#x2019;&#xEE;le subtropicale de Yoron ; Franchir les portes sacr&#xE9;es au Fushimi&#x2011;Inari Taisha ; Vibrer avec les Japonais &#xE0; un combat de sumo ... - Les bonnes adresses pour tous les budgets :&#xA0;se restaurer, prendre un verre, shopping, sortir, se loger - Les meilleurs spots en famille (activit&#xE9;s pour les 6-14 ans) :&#xA0;Plong&#xE9;e dans la magie des anime ; Promenade au milieu des cerfs Sika ; Vir&#xE9;e dans le d&#xE9;sert &#xE0; dos de chameau ... - Des suggestions d&#x2019;itin&#xE9;raires :&#xA0;Cap au sud : Kyushu et les archipels en 20 jours ; La route du Tokaido en 14 jours ; Autour de la mer Int&#xE9;rieure en 10 jours ... - De nombreux cartes et plans&#xA0;pour retrouver les principaux sites &#xE9;toil&#xE9;s de la destination. - Les plus :&#xA0;120 activit&#xE9;s en famille - Toutes les infos mises &#xE0; jour&#xA0;dans cette nouvelle &#xE9;dition Ce guide est divis&#xE9; en 9 micro-r&#xE9;gions :&#xA0;Tokyo et sa r&#xE9;gion ; Centre de Honshu (Chubu) ; Kyoto et le Kansai ; Ouest de Honshu (Chugoku) ; Nord de Honshu (Tohoku) ; Hokkaido ; Shikoku ; Kyushu ; Les archipels du Sud. Pensez &#xE0; utilisez en compl&#xE9;ment notre&#xA0;Carte National Japon n&#xB0;802, notre Guide Vert Week&amp;GO Tokyo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Boutique de l&#039;Aventure Michelin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/laventuremichelin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T09:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2026\/03\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/\",\"url\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/\",\"name\":\"Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg\",\"datePublished\":\"2026-03-31T12:13:38+00:00\",\"dateModified\":\"2026-04-14T09:35:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg\",\"contentUrl\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg\",\"width\":1000,\"height\":1724},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/product\\\/guide-vert-japon-ebook-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guide Vert Japon &#8211; ebook\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/\",\"name\":\"Boutique de l&#039;Aventure Michelin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#organization\",\"name\":\"Boutique de l'Aventure Michelin\",\"url\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LOGO_LAVENTURE_MFP_VER_PASTILLES_RVB@2x.jpg\",\"contentUrl\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LOGO_LAVENTURE_MFP_VER_PASTILLES_RVB@2x.jpg\",\"width\":1292,\"height\":1044,\"caption\":\"Boutique de l'Aventure Michelin\"},\"image\":{\"@id\":\"https:\\\/\\\/boutique.laventure.michelin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-fr.facebook.com\\\/laventuremichelin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/","og_locale":"en_US","og_type":"article","og_title":"Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin","og_description":"Laissez-vous guider par nos auteurs ! Au cours de leurs innombrables tourn&#xE9;es, ils ont d&#xE9;nich&#xE9; pour vous des lieux inoubliables ou insolites : - Les incontournables (class&#xE9;s 1, 2 ou 3 &#xE9;toiles) :&#xA0;Kyoto***, Le mont Fuji***, Baie de Kabira*** ... - Les coups de coeur :&#xA0;Plonger dans les eaux transparentes de l&#x2019;&#xEE;le subtropicale de Yoron ; Franchir les portes sacr&#xE9;es au Fushimi&#x2011;Inari Taisha ; Vibrer avec les Japonais &#xE0; un combat de sumo ... - Les bonnes adresses pour tous les budgets :&#xA0;se restaurer, prendre un verre, shopping, sortir, se loger - Les meilleurs spots en famille (activit&#xE9;s pour les 6-14 ans) :&#xA0;Plong&#xE9;e dans la magie des anime ; Promenade au milieu des cerfs Sika ; Vir&#xE9;e dans le d&#xE9;sert &#xE0; dos de chameau ... - Des suggestions d&#x2019;itin&#xE9;raires :&#xA0;Cap au sud : Kyushu et les archipels en 20 jours ; La route du Tokaido en 14 jours ; Autour de la mer Int&#xE9;rieure en 10 jours ... - De nombreux cartes et plans&#xA0;pour retrouver les principaux sites &#xE9;toil&#xE9;s de la destination. - Les plus :&#xA0;120 activit&#xE9;s en famille - Toutes les infos mises &#xE0; jour&#xA0;dans cette nouvelle &#xE9;dition Ce guide est divis&#xE9; en 9 micro-r&#xE9;gions :&#xA0;Tokyo et sa r&#xE9;gion ; Centre de Honshu (Chubu) ; Kyoto et le Kansai ; Ouest de Honshu (Chugoku) ; Nord de Honshu (Tohoku) ; Hokkaido ; Shikoku ; Kyushu ; Les archipels du Sud. Pensez &#xE0; utilisez en compl&#xE9;ment notre&#xA0;Carte National Japon n&#xB0;802, notre Guide Vert Week&amp;GO Tokyo.","og_url":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/","og_site_name":"Boutique de l&#039;Aventure Michelin","article_publisher":"https:\/\/fr-fr.facebook.com\/laventuremichelin\/","article_modified_time":"2026-04-14T09:35:49+00:00","og_image":[{"width":1000,"height":1724,"url":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2026\/03\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/","url":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/","name":"Guide Vert Japon - ebook - Boutique de l&#039;Aventure Michelin","isPartOf":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/#primaryimage"},"image":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/#primaryimage"},"thumbnailUrl":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2026\/03\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg","datePublished":"2026-03-31T12:13:38+00:00","dateModified":"2026-04-14T09:35:49+00:00","breadcrumb":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/#primaryimage","url":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2026\/03\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg","contentUrl":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2026\/03\/a8201c77d2cd355bb3f382797319afdcfd6223-4.jpg","width":1000,"height":1724},{"@type":"BreadcrumbList","@id":"https:\/\/boutique.laventure.michelin.com\/en\/product\/guide-vert-japon-ebook-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boutique.laventure.michelin.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/boutique.laventure.michelin.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Guide Vert Japon &#8211; ebook"}]},{"@type":"WebSite","@id":"https:\/\/boutique.laventure.michelin.com\/en\/#website","url":"https:\/\/boutique.laventure.michelin.com\/en\/","name":"Boutique de l&#039;Aventure Michelin","description":"","publisher":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boutique.laventure.michelin.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/boutique.laventure.michelin.com\/en\/#organization","name":"Boutique de l'Aventure Michelin","url":"https:\/\/boutique.laventure.michelin.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boutique.laventure.michelin.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2020\/12\/LOGO_LAVENTURE_MFP_VER_PASTILLES_RVB@2x.jpg","contentUrl":"https:\/\/boutique.laventure.michelin.com\/wp-content\/uploads\/2020\/12\/LOGO_LAVENTURE_MFP_VER_PASTILLES_RVB@2x.jpg","width":1292,"height":1044,"caption":"Boutique de l'Aventure Michelin"},"image":{"@id":"https:\/\/boutique.laventure.michelin.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/laventuremichelin\/"]}]}},"_links":{"self":[{"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/product\/48257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/comments?post=48257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/media\/48255"}],"wp:attachment":[{"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/media?parent=48257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/product_brand?post=48257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/product_cat?post=48257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/boutique.laventure.michelin.com\/en\/wp-json\/wp\/v2\/product_tag?post=48257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}